{"id":80,"count":1,"description":"","link":"https:\/\/www.ferroplan.fi\/blogi\/blog\/tag\/kuljetin\/","name":"kuljetin","slug":"kuljetin","taxonomy":"post_tag","meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v17.8 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.ferroplan.fi\/blogi\/blog\/tag\/kuljetin\/\" \/>\n<meta property=\"og:locale\" content=\"fi_FI\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"kuljetin Archives - Ei mit\u00e4\u00e4n rimpuloita -blogi\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.ferroplan.fi\/blogi\/blog\/tag\/kuljetin\/\" \/>\n<meta property=\"og:site_name\" content=\"Ei mit\u00e4\u00e4n rimpuloita -blogi\" \/>\n<meta name=\"twitter:card\" content=\"summary\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.ferroplan.fi\/blogi\/#website\",\"url\":\"https:\/\/www.ferroplan.fi\/blogi\/\",\"name\":\"Ei mit\\u00e4\\u00e4n rimpuloita -blogi\",\"description\":\"Suomen ainoa teollisuusblogi\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.ferroplan.fi\/blogi\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"fi\"},{\"@type\":\"CollectionPage\",\"@id\":\"https:\/\/www.ferroplan.fi\/blogi\/blog\/tag\/kuljetin\/#webpage\",\"url\":\"https:\/\/www.ferroplan.fi\/blogi\/blog\/tag\/kuljetin\/\",\"name\":\"kuljetin Archives - Ei mit\\u00e4\\u00e4n rimpuloita -blogi\",\"isPartOf\":{\"@id\":\"https:\/\/www.ferroplan.fi\/blogi\/#website\"},\"breadcrumb\":{\"@id\":\"https:\/\/www.ferroplan.fi\/blogi\/blog\/tag\/kuljetin\/#breadcrumb\"},\"inLanguage\":\"fi\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.ferroplan.fi\/blogi\/blog\/tag\/kuljetin\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.ferroplan.fi\/blogi\/blog\/tag\/kuljetin\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.ferroplan.fi\/blogi\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"kuljetin\"}]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.ferroplan.fi\/blogi\/blog\/tag\/kuljetin\/","og_locale":"fi_FI","og_type":"article","og_title":"kuljetin Archives - Ei mit\u00e4\u00e4n rimpuloita -blogi","og_url":"https:\/\/www.ferroplan.fi\/blogi\/blog\/tag\/kuljetin\/","og_site_name":"Ei mit\u00e4\u00e4n rimpuloita -blogi","twitter_card":"summary","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebSite","@id":"https:\/\/www.ferroplan.fi\/blogi\/#website","url":"https:\/\/www.ferroplan.fi\/blogi\/","name":"Ei mit\u00e4\u00e4n rimpuloita -blogi","description":"Suomen ainoa teollisuusblogi","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.ferroplan.fi\/blogi\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"fi"},{"@type":"CollectionPage","@id":"https:\/\/www.ferroplan.fi\/blogi\/blog\/tag\/kuljetin\/#webpage","url":"https:\/\/www.ferroplan.fi\/blogi\/blog\/tag\/kuljetin\/","name":"kuljetin Archives - Ei mit\u00e4\u00e4n rimpuloita -blogi","isPartOf":{"@id":"https:\/\/www.ferroplan.fi\/blogi\/#website"},"breadcrumb":{"@id":"https:\/\/www.ferroplan.fi\/blogi\/blog\/tag\/kuljetin\/#breadcrumb"},"inLanguage":"fi","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.ferroplan.fi\/blogi\/blog\/tag\/kuljetin\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.ferroplan.fi\/blogi\/blog\/tag\/kuljetin\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.ferroplan.fi\/blogi\/"},{"@type":"ListItem","position":2,"name":"kuljetin"}]}]}},"_links":{"self":[{"href":"https:\/\/www.ferroplan.fi\/blogi\/wp-json\/wp\/v2\/tags\/80"}],"collection":[{"href":"https:\/\/www.ferroplan.fi\/blogi\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/www.ferroplan.fi\/blogi\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/www.ferroplan.fi\/blogi\/wp-json\/wp\/v2\/posts?tags=80"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}